{"id":5979,"date":"2020-04-16T11:56:23","date_gmt":"2020-04-16T09:56:23","guid":{"rendered":"https:\/\/swissvoicetour.smartfox-adtech.ch\/?page_id=5979"},"modified":"2020-04-16T14:48:36","modified_gmt":"2020-04-16T12:48:36","slug":"les-charpentiers","status":"publish","type":"page","link":"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/stagioni-precedenti\/stagione-6\/les-charpentiers\/","title":{"rendered":"Les Charpentiers"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7m0uc4i-42ab96b437fefc62e751ba5c15e899ea\">\n.avia-section.av-k7m0uc4i-42ab96b437fefc62e751ba5c15e899ea{\nbackground-color:#cca047;\nbackground-image:unset;\n}\n.avia-section.av-k7m0uc4i-42ab96b437fefc62e751ba5c15e899ea .av-extra-border-element .av-extra-border-inner{\nbackground-color:#ffffff;\n}\n<\/style>\n<div id='av_section_1'  class='avia-section av-k7m0uc4i-42ab96b437fefc62e751ba5c15e899ea main_color avia-section-default avia-no-border-styling  avia-builder-el-0  el_before_av_section  avia-builder-el-first  avia-bg-style-scroll av-minimum-height av-minimum-height-custom av-height-custom  container_wrap fullsize'   data-av_minimum_height_px='200'><div class='container av-section-cont-open' style='height:200px'><main  role=\"main\" itemprop=\"mainContentOfPage\"  class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-5979'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k92rem1y-ff4651c0d796814480a5a9c4e68f7b7b\">\n#top .av-special-heading.av-k92rem1y-ff4651c0d796814480a5a9c4e68f7b7b{\npadding-bottom:10px;\ncolor:#ffffff;\n}\nbody .av-special-heading.av-k92rem1y-ff4651c0d796814480a5a9c4e68f7b7b .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-k92rem1y-ff4651c0d796814480a5a9c4e68f7b7b .special-heading-inner-border{\nborder-color:#ffffff;\n}\n.av-special-heading.av-k92rem1y-ff4651c0d796814480a5a9c4e68f7b7b .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-k92rem1y-ff4651c0d796814480a5a9c4e68f7b7b av-special-heading-h1 custom-color-heading blockquote modern-quote  avia-builder-el-1  avia-builder-el-no-sibling '><h1 class='av-special-heading-tag '  itemprop=\"headline\"  >Les Charpentiers<\/h1><div class='av_custom_color av-subheading av-subheading_below'><p>Morges &#8211; Stagione 6<\/p>\n<\/div><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div>\n<\/div><\/div><\/main><!-- close content main element --><\/div><div class='av-extra-border-element border-extra-diagonal border-extra-diagonal-inverse '><div class='av-extra-border-outer'><div class='av-extra-border-inner'><\/div><\/div><\/div><\/div><div id='av_section_2'  class='avia-section av-g1rox-68c6bb8ccff6827f2aa3c50ffa4e4072 main_color avia-section-default avia-no-border-styling  avia-builder-el-2  el_after_av_section  avia-builder-el-last  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-5979'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-bkkg9-a89728ed957b1d9868369d986c5eb249\">\n.flex_column.av-bkkg9-a89728ed957b1d9868369d986c5eb249{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-bkkg9-a89728ed957b1d9868369d986c5eb249 av_one_fifth  avia-builder-el-3  el_before_av_three_fifth  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><div  class='avia-button-wrap av-k7ngtdap-63515f3494e8cde9c6f5bf1b01459709-wrap avia-button-left  avia-builder-el-4  avia-builder-el-no-sibling '><a href='https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/stagioni-precedenti\/stagione-6\/'  class='avia-button av-k7ngtdap-63515f3494e8cde9c6f5bf1b01459709 av-link-btn avia-icon_select-yes-left-icon avia-size-small avia-position-left avia-color-theme-color'   aria-label=\"Stagione 6\"><span class='avia_button_icon avia_button_icon_left' aria-hidden='true' data-av_icon='\ue830' data-av_iconfont='entypo-fontello'><\/span><span class='avia_iconbox_title' >Stagione 6<\/span><\/a><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-bkkg9-d25ce05022cab2ca5ca5d47f01d51633\">\n.flex_column.av-bkkg9-d25ce05022cab2ca5ca5d47f01d51633{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-bkkg9-d25ce05022cab2ca5ca5d47f01d51633 av_three_fifth  avia-builder-el-5  el_after_av_one_fifth  el_before_av_one_fifth  flex_column_div av-zero-column-padding  '     ><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-bkkg9-d25ce05022cab2ca5ca5d47f01d51633\">\n.flex_column.av-bkkg9-d25ce05022cab2ca5ca5d47f01d51633{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-bkkg9-d25ce05022cab2ca5ca5d47f01d51633 av_one_fifth  avia-builder-el-6  el_after_av_three_fifth  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-7  el_after_av_one_fifth  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-af240a72e99ed83a3055d6c1f9fae05f\">\n.flex_column.av-gbo69-af240a72e99ed83a3055d6c1f9fae05f{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-af240a72e99ed83a3055d6c1f9fae05f av_one_third  avia-builder-el-8  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-b1bfdb3b9f0d9f4cf459641300a2d6c8 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/n7JrybqSS78'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Giorgia - Swiss Voice Tour  - Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/n7JrybqSS78?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-10  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-fc4894c4747726111023b07e2eaa3120 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/WHPoPTvzQxE'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Vera  - Swiss Voice Tour  -   Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/WHPoPTvzQxE?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-12  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-8d6d8fb42c4da4cb5c50d9ffe7778de7 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/VpCMzpyD6Uo'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Agata - Swiss Voice Tour - Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/VpCMzpyD6Uo?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-14  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-af240a72e99ed83a3055d6c1f9fae05f\">\n.flex_column.av-gbo69-af240a72e99ed83a3055d6c1f9fae05f{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-af240a72e99ed83a3055d6c1f9fae05f av_one_third  avia-builder-el-15  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-f9fc370a12287d3ae5655fcf75003e87 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/LspuAZVyFRo'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Prithvi - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/LspuAZVyFRo?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-17  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-3f0c5de809ae31210513e0bdcb03e642 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/kRzvfiI1OBg'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Lucie - Swiss Voice Tour - Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/kRzvfiI1OBg?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-19  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-bf3c26d7773a689474ab83065e61baa1 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/Q_mWfm-aeRc'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"L\u00e9a - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/Q_mWfm-aeRc?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-21  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-af240a72e99ed83a3055d6c1f9fae05f\">\n.flex_column.av-gbo69-af240a72e99ed83a3055d6c1f9fae05f{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-af240a72e99ed83a3055d6c1f9fae05f av_one_third  avia-builder-el-22  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-e21431987eca00724a1bd86c72160a91 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/CkPZxHSe2iE'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Katarina - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/CkPZxHSe2iE?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-24  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-2970a2df08f9fbf34702e6d668df9e23 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/3LHLNUv_bfU'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Elisabeth - Swiss Voice Tour - Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/3LHLNUv_bfU?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-26  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-15118f90be93b196574a64776b21447f avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/kSovWKk0JFY'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Anaelle &amp; Vincent - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/kSovWKk0JFY?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-28  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-af240a72e99ed83a3055d6c1f9fae05f\">\n.flex_column.av-gbo69-af240a72e99ed83a3055d6c1f9fae05f{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-af240a72e99ed83a3055d6c1f9fae05f av_one_third  avia-builder-el-29  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-54b5e46362cbfb6c92e2c40f8a3dd848 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/9IXPttGXp3k'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Montse - Swiss Voice Tour - Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/9IXPttGXp3k?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-31  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-5008207d2ff0dbd64a54b578cfae9c80 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/oN1rdjlQaEk'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Kelly - Swiss Voice Tour - Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/oN1rdjlQaEk?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-33  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-12eb87f892f41b302d455a9f5ee1c691 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/ws6rFHv2n7Y'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Fran\u00e7ois - Swiss Voice Tour  -   Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/ws6rFHv2n7Y?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-35  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-af240a72e99ed83a3055d6c1f9fae05f\">\n.flex_column.av-gbo69-af240a72e99ed83a3055d6c1f9fae05f{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-af240a72e99ed83a3055d6c1f9fae05f av_one_third  avia-builder-el-36  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-570793e90653e0f1c032c28d70df2b6a avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/2h2n0RR9D5c'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Andre - Swiss Voice Tour  -   Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/2h2n0RR9D5c?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-38  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-26aea081d6d2af9ebdeeaf2dd2fc8b65 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/HCJjYqh4en8'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Lola - Swiss Voice Tour  -   Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/HCJjYqh4en8?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-40  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-6f0d62d26248d27f0439ba61baef1282 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/25cKQ0Ji8jo'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Noemie - Swiss Voice Tour  -   Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/25cKQ0Ji8jo?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-42  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-af240a72e99ed83a3055d6c1f9fae05f\">\n.flex_column.av-gbo69-af240a72e99ed83a3055d6c1f9fae05f{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-af240a72e99ed83a3055d6c1f9fae05f av_one_third  avia-builder-el-43  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-ead30f65fe980d99b3b86830d0c30a2a avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/QbQP3bbdISQ'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Yves - Swiss Voice Tour  -   Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/QbQP3bbdISQ?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-45  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-9cdb662426543814f682380c20f9fef6 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/jI13UNWssds'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Julia - Swiss Voice Tour - Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/jI13UNWssds?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-47  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-7a80d16baacfdc3cce58a0f13f01c777 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/VIncw4Jjs6Q'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Jean Daniel - Swiss Voice Tour   -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/VIncw4Jjs6Q?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-49  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-af240a72e99ed83a3055d6c1f9fae05f\">\n.flex_column.av-gbo69-af240a72e99ed83a3055d6c1f9fae05f{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-af240a72e99ed83a3055d6c1f9fae05f av_one_third  avia-builder-el-50  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-8fc2a94873eac3de6ab9ed42c4236f0a avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/hBTexJns5xg'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Alberic - Swiss Voice Tour  -   Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/hBTexJns5xg?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-52  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-6eb9a77aff4554d20d5195f8fc92d4ae avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/chZ8JimBILc'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Melodi - Swiss Voice Tour  -   Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/chZ8JimBILc?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-54  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-ebfd64307751826d9ca562667886fdf6 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/ZwxuCYh53-M'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Oliver - Swiss Voice Tour  -   Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/ZwxuCYh53-M?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-56  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-af240a72e99ed83a3055d6c1f9fae05f\">\n.flex_column.av-gbo69-af240a72e99ed83a3055d6c1f9fae05f{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-af240a72e99ed83a3055d6c1f9fae05f av_one_third  avia-builder-el-57  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-d13b8efba76eb5a9c244cbfb61545a43 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/tz2gXe5KAeA'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Loi\u0308c -  Swiss Voice Tour  -   Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/tz2gXe5KAeA?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-59  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-bca319d211a9a8090196c861a75d77ea avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/4Sl7g7M-h8s'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Elodie -  Swiss Voice Tour  -   Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/4Sl7g7M-h8s?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-61  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-b111d4a7d63a85ac0207d20d985f19f1 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/v7ds5pDFAAk'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Laura - Swiss Voice Tour  -   Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/v7ds5pDFAAk?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-63  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-af240a72e99ed83a3055d6c1f9fae05f\">\n.flex_column.av-gbo69-af240a72e99ed83a3055d6c1f9fae05f{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-af240a72e99ed83a3055d6c1f9fae05f av_one_third  avia-builder-el-64  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-563e793a2d513b2d4860615c71168641 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/s31DnB6489Q'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Clarisse -   Swiss Voice Tour  -   Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/s31DnB6489Q?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-66  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-b9ed8164951f4e33ae868251aa7de256 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/NrIaD03l6JQ'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Elsa - Swiss Voice Tour   -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/NrIaD03l6JQ?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-68  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-20d64f2bac95d555a2ffcba109255011 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/twJXeFN2iG0'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Emily - Swiss Voice Tour  -   Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/twJXeFN2iG0?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-70  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-af240a72e99ed83a3055d6c1f9fae05f\">\n.flex_column.av-gbo69-af240a72e99ed83a3055d6c1f9fae05f{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-af240a72e99ed83a3055d6c1f9fae05f av_one_third  avia-builder-el-71  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-c5e119a59f73d75510489f86c22848aa avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/p0968fItDFY'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Laurent - Swiss Voice Tour  -   Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/p0968fItDFY?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-73  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-15689acbd018ec5a3cf3afdbe724b900 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/OD2L8oaSeqc'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Sophia &amp; Olivia - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/OD2L8oaSeqc?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-75  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-38c30bd9b4117a9c66df825bda797b0c avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/A5pJNsagYXA'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Oliver - Swiss Voice Tour  -   Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/A5pJNsagYXA?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-77  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-af240a72e99ed83a3055d6c1f9fae05f\">\n.flex_column.av-gbo69-af240a72e99ed83a3055d6c1f9fae05f{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-af240a72e99ed83a3055d6c1f9fae05f av_one_third  avia-builder-el-78  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-c20a67d24ce8a375b2c28d61e4e9f8a3 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/oKnkKK_FD1k'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Peggy - Swiss Voice Tour  -   Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/oKnkKK_FD1k?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-80  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-543c341957a19df428f69dbda853747a avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/-jDn0HPnxLg'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Ashley -  Swiss Voice Tour -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/-jDn0HPnxLg?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-82  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-2740bcdb4fcfea58a8c250229d6d772a avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/CmRcJ4IfH5k'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Diane - Swiss Voice Tour  -   Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/CmRcJ4IfH5k?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-84  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-af240a72e99ed83a3055d6c1f9fae05f\">\n.flex_column.av-gbo69-af240a72e99ed83a3055d6c1f9fae05f{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-af240a72e99ed83a3055d6c1f9fae05f av_one_third  avia-builder-el-85  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-35778e618ee3428cde319072cdeaf2e0 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/TBbDySXpCRw'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Alyssa - Swiss Voice Tour  -   Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/TBbDySXpCRw?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-87  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-ff4a4cfcab8efb852fffde7ac766f956 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/N8ySTwSV-30'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Doris - Swiss Voice Tour  -   Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/N8ySTwSV-30?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-89  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-253f38beefbd78fe1def4fa4298cf372 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/Z4jPb7xLK6Q'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Tiffany -  Swiss Voice Tour  -   Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/Z4jPb7xLK6Q?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-91  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-af240a72e99ed83a3055d6c1f9fae05f\">\n.flex_column.av-gbo69-af240a72e99ed83a3055d6c1f9fae05f{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-af240a72e99ed83a3055d6c1f9fae05f av_one_third  avia-builder-el-92  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-dc12c1875d7ba1566f30c2576f07f682 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/KKL2NYRmk5k'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Fabio  -  Swiss Voice Tour     Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/KKL2NYRmk5k?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-94  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-c3bd87708e9275f4f636c6ecd2716dbe avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/d8rtAtuP5Ms'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Alicia  -  Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/d8rtAtuP5Ms?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-96  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-f8939cd90705693c642530e858b1dcfe avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/7oGaoGPmQcw'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Arina - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/7oGaoGPmQcw?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-98  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-af240a72e99ed83a3055d6c1f9fae05f\">\n.flex_column.av-gbo69-af240a72e99ed83a3055d6c1f9fae05f{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-af240a72e99ed83a3055d6c1f9fae05f av_one_third  avia-builder-el-99  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-631743676c897496ca938c8045b43ea7 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/xrZTqvO9qsA'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Chaima - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/xrZTqvO9qsA?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-101  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-d3c6bf6c02b53078049428d66a24063e avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/iUt2a7aXKbY'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Maxime - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/iUt2a7aXKbY?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-103  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-191ef648a49b6adc61c4cc02b914fd9b avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/TlmEmeVh1h0'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Nicole - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/TlmEmeVh1h0?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-105  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-af240a72e99ed83a3055d6c1f9fae05f\">\n.flex_column.av-gbo69-af240a72e99ed83a3055d6c1f9fae05f{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-af240a72e99ed83a3055d6c1f9fae05f av_one_third  avia-builder-el-106  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-9af0860096e17f5e654b4f1b70f271a8 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/pqaMmX4F3nQ'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Barbara - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/pqaMmX4F3nQ?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-108  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-8e673fce1ad990525bb664536b7742e5 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/K2mD2KK5DFQ'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Floriana - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/K2mD2KK5DFQ?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-110  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-3addcb6c212d78003ca10a450156d80f avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/bGprUuCS9uc'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Etienne - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/bGprUuCS9uc?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-112  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-af240a72e99ed83a3055d6c1f9fae05f\">\n.flex_column.av-gbo69-af240a72e99ed83a3055d6c1f9fae05f{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-af240a72e99ed83a3055d6c1f9fae05f av_one_third  avia-builder-el-113  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-c8f46e976bfbf33e0c8e25683a1abaed avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/8hFbC7uDkh4'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Lyria - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/8hFbC7uDkh4?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-115  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-4e8bfdbb503086fb616187ee0865e0e8 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/3od5mQkdwNE'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Tatiana - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/3od5mQkdwNE?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-117  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-80aed6c0da3d3608752e27110d5078b2 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/KlQxslkWnRM'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Renzo - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/KlQxslkWnRM?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-119  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-af240a72e99ed83a3055d6c1f9fae05f\">\n.flex_column.av-gbo69-af240a72e99ed83a3055d6c1f9fae05f{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-af240a72e99ed83a3055d6c1f9fae05f av_one_third  avia-builder-el-120  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-aae6f4afbf648a91a4534b073038a98b avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/dqxEOQr4XkY'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Yasmine - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/dqxEOQr4XkY?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-122  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-1cff822a4fb875b26315ee0c38443b3f avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/Mfa9fcDNuZ4'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Florent - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/Mfa9fcDNuZ4?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-124  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-7b7a97cf252c8d2f603de8750eeebc29 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/0pgWaxu20AE'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Antonino - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/0pgWaxu20AE?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-126  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-af240a72e99ed83a3055d6c1f9fae05f\">\n.flex_column.av-gbo69-af240a72e99ed83a3055d6c1f9fae05f{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-af240a72e99ed83a3055d6c1f9fae05f av_one_third  avia-builder-el-127  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-f87c42e3b54fe869ae9086ba6b8ffe67 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/14bBMgxxH68'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Josee - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/14bBMgxxH68?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-129  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-3aadd586782ba96704b309473b16eebd avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/zG4xe5mErXg'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Caroline - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/zG4xe5mErXg?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-131  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-6b13a3b43d627dfa5e7e90b07cd45758 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/wnythEbr5oM'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Andre - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/wnythEbr5oM?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-133  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-af240a72e99ed83a3055d6c1f9fae05f\">\n.flex_column.av-gbo69-af240a72e99ed83a3055d6c1f9fae05f{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-af240a72e99ed83a3055d6c1f9fae05f av_one_third  avia-builder-el-134  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-a48f7ea3af8d3650ba853eff0da5aeb8 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/28Bi55130jY'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Clara - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/28Bi55130jY?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-136  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-7cb477a04aab56f30b4135834a41031e avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/wKQtd-cEZmU'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Luca - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/wKQtd-cEZmU?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-138  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-a435fca1583f13fdba012ed26c30692a avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/49TM_3gsLkY'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Sandra - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/49TM_3gsLkY?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-140  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-af240a72e99ed83a3055d6c1f9fae05f\">\n.flex_column.av-gbo69-af240a72e99ed83a3055d6c1f9fae05f{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-af240a72e99ed83a3055d6c1f9fae05f av_one_third  avia-builder-el-141  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-5d26f7e9b2b6c2be83935616b372feb9 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/8tZ2IehZiq8'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Blerim - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/8tZ2IehZiq8?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-143  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-31a3dd6d64a618e0f8e21a957eba0c80 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/c460gTK9E2c'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Leslie - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/c460gTK9E2c?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-145  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-0cf57dcd2503807882e83a9e284a1f00 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/OnEVtEAnC6M'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Marine  - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/OnEVtEAnC6M?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-147  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-af240a72e99ed83a3055d6c1f9fae05f\">\n.flex_column.av-gbo69-af240a72e99ed83a3055d6c1f9fae05f{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-af240a72e99ed83a3055d6c1f9fae05f av_one_third  avia-builder-el-148  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-ebd0feb4bb1669ea725c2b880acb38a5 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/TBxOwAsc5_g'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Sidina - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/TBxOwAsc5_g?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-150  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-9d4c47817871479921dc4a871e314f43 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/xHv3FHIBz_I'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"S\u00e9bastien - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/xHv3FHIBz_I?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-152  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-c115fc87b2db6d9bee6c9bfb0b71869f avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/O47w2XcQ27o'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Emelyne  - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/O47w2XcQ27o?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-154  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-af240a72e99ed83a3055d6c1f9fae05f\">\n.flex_column.av-gbo69-af240a72e99ed83a3055d6c1f9fae05f{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-af240a72e99ed83a3055d6c1f9fae05f av_one_third  avia-builder-el-155  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-fabed2f6613f177993da67ef24c7e8dd avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/zU_TDiObgCk'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Cynthia - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/zU_TDiObgCk?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-157  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-96dd61cd0f98db962ba42dce59f96d37 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/05z-L147R78'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Charlotte - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/05z-L147R78?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-159  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-8a29a1caa146f5d39bed9318b6174fcf avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/FScEaUHAcyU'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Xavier - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/FScEaUHAcyU?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-161  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-af240a72e99ed83a3055d6c1f9fae05f\">\n.flex_column.av-gbo69-af240a72e99ed83a3055d6c1f9fae05f{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-af240a72e99ed83a3055d6c1f9fae05f av_one_third  avia-builder-el-162  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-473580d31c5e912a0a0a980093fcfce4 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/pKD_BsC0CME'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Brittany - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/pKD_BsC0CME?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-164  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-b73e6bef35539d90c460339f24df283e avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/LQ6yPRILXxo'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Fleuranne - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/LQ6yPRILXxo?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-166  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-928cbf68edbf498a8ded1ef1167b30f3 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/ytkcrhnSCtk'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Elisa  - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/ytkcrhnSCtk?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-168  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-af240a72e99ed83a3055d6c1f9fae05f\">\n.flex_column.av-gbo69-af240a72e99ed83a3055d6c1f9fae05f{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-af240a72e99ed83a3055d6c1f9fae05f av_one_third  avia-builder-el-169  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-0902db95c8883415a4dbfad0c677ff77 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/2PVZ_P4gj64'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Morgane  - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/2PVZ_P4gj64?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-171  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-17f2a9292755ed1f55b8718b1ea5d3fd avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/B4VzeSfut74'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Guillaume - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/B4VzeSfut74?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-173  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-9b6f3dd7c049bcb5bcb8cc0ee1bb10a2 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/iYLN0Sv7qNM'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Johanna - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/iYLN0Sv7qNM?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-175  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-af240a72e99ed83a3055d6c1f9fae05f\">\n.flex_column.av-gbo69-af240a72e99ed83a3055d6c1f9fae05f{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-af240a72e99ed83a3055d6c1f9fae05f av_one_third  avia-builder-el-176  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-d5517bc050c557394628faca81b5eea4 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/HIDdfcZW3ww'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"L\u00e9ana - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/HIDdfcZW3ww?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-178  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-5faea47343e3dae2582cc91ebaba911e avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/wpkeZqKS2YU'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Sara - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/wpkeZqKS2YU?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-180  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-879343a903c0178d0dd983b776e4a1fb avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/E5yQNIe7VGU'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Isabelle - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/E5yQNIe7VGU?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-182  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-af240a72e99ed83a3055d6c1f9fae05f\">\n.flex_column.av-gbo69-af240a72e99ed83a3055d6c1f9fae05f{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-af240a72e99ed83a3055d6c1f9fae05f av_one_third  avia-builder-el-183  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-59625bc50608792598e16d7a2cf6ca4c avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/KHcV6Nl-Nvs'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Marion - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/KHcV6Nl-Nvs?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-185  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-59e42bf671f36d45a3ca39f344e62eb2 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/Ss39MADSRvQ'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Luana - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/Ss39MADSRvQ?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-187  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-9a56d00f0c4f5612a3aceef27d1627e9 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/pKECZUGCzJk'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Florimond  - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/pKECZUGCzJk?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-189  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-af240a72e99ed83a3055d6c1f9fae05f\">\n.flex_column.av-gbo69-af240a72e99ed83a3055d6c1f9fae05f{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-af240a72e99ed83a3055d6c1f9fae05f av_one_third  avia-builder-el-190  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-ff1306d75c2fe215128f38d8cc457857 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/MH6J7j3Hu9w'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Natalia - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/MH6J7j3Hu9w?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-192  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-fe8b89546a304100af10f03e2993bbe8 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/MKeDd0QJnho'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"L\u00e9na - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/MKeDd0QJnho?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-194  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-63de13b63b7d0558edde657185be89b5 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/hiheo91HeFY'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Elisabeth - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/hiheo91HeFY?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-196  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-af240a72e99ed83a3055d6c1f9fae05f\">\n.flex_column.av-gbo69-af240a72e99ed83a3055d6c1f9fae05f{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-af240a72e99ed83a3055d6c1f9fae05f av_one_third  avia-builder-el-197  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-d957af2e1bcbbf653554d71d8e99b835 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/mrX_Je6SLTA'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Jennifer - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/mrX_Je6SLTA?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-199  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-872bfcc57852e11b61fedca135fff618 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/LFW6sDyr3IY'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Paul  - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/LFW6sDyr3IY?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-201  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-fa2f0c9db1e970406230e9f553f5f47a avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/84T-NwImrdY'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Aur\u00e9lie  - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/84T-NwImrdY?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-203  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-af240a72e99ed83a3055d6c1f9fae05f\">\n.flex_column.av-gbo69-af240a72e99ed83a3055d6c1f9fae05f{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-af240a72e99ed83a3055d6c1f9fae05f av_one_third  avia-builder-el-204  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-7c2ad4a9f0218cd1fa0ecec7f2085e2b avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/uFffuXNuM_w'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Clara  - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/uFffuXNuM_w?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-206  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-e8c6f40bdf89a0736a549fbfe1ac27a6 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/kr4q1LI213c'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"St\u00e9phane  - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/kr4q1LI213c?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-208  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-0b6bf4b3c40068c6081088630f62ecfd avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/Nc2qjOIy2u0'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Camille - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/Nc2qjOIy2u0?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-210  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-af240a72e99ed83a3055d6c1f9fae05f\">\n.flex_column.av-gbo69-af240a72e99ed83a3055d6c1f9fae05f{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-af240a72e99ed83a3055d6c1f9fae05f av_one_third  avia-builder-el-211  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-e639723359756d7d601417728571bc21 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/iZa2gbQIHiQ'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Audrey  - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/iZa2gbQIHiQ?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-213  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-3c03a13fa0c24ee2688cf5cdd6e58c91 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/VTZNH_N4nug'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Charlie - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/VTZNH_N4nug?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-215  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-a28bf2d3c7212212d175f81a8f0599df avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/zKzZF3TZApU'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Mariam - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/zKzZF3TZApU?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-217  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-af240a72e99ed83a3055d6c1f9fae05f\">\n.flex_column.av-gbo69-af240a72e99ed83a3055d6c1f9fae05f{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-af240a72e99ed83a3055d6c1f9fae05f av_one_third  avia-builder-el-218  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-5eb5425641b619f3878746409e1fe148 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/tSWD5VZdfGg'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Th\u00e9odore - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/tSWD5VZdfGg?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-220  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-53c9eef856117a453d0ed8ae3b99ebb7 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/2I6pJ0sIunM'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Brandy - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/2I6pJ0sIunM?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-222  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-140c6d4be35e40aa4c093881b8b6d9f8 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/Md-iS4xL878'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Rasha - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/Md-iS4xL878?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-224  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-af240a72e99ed83a3055d6c1f9fae05f\">\n.flex_column.av-gbo69-af240a72e99ed83a3055d6c1f9fae05f{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-af240a72e99ed83a3055d6c1f9fae05f av_one_third  avia-builder-el-225  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-833c972f2b0522821a80c43b95e62c1a avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/BXTf8F93nFo'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Marjolaine - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/BXTf8F93nFo?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-227  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-1dc4889d5c8de696439f0bb15391be0e avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/8qbMikEmeSc'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Jordane - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/8qbMikEmeSc?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-229  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-a72f1757f10d2118caaf324cd5dd9902 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/8gsqgi8lAXI'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Erik - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/8gsqgi8lAXI?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-231  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-af240a72e99ed83a3055d6c1f9fae05f\">\n.flex_column.av-gbo69-af240a72e99ed83a3055d6c1f9fae05f{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-af240a72e99ed83a3055d6c1f9fae05f av_one_third  avia-builder-el-232  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-f89e1a8fd1115205ea5790f01c3d39d9 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/W22qJlABAaM'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Yngrid Ysabel - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/W22qJlABAaM?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-234  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-739173ba0a82e76ded229983a94dd8ff avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/y7F5vxTl9CE'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Phenicia - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/y7F5vxTl9CE?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-236  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-c925c4dbc27648a78011f26834d4bd26 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/vbsfHibI1ik'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Antony - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/vbsfHibI1ik?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-238  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-af240a72e99ed83a3055d6c1f9fae05f\">\n.flex_column.av-gbo69-af240a72e99ed83a3055d6c1f9fae05f{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-af240a72e99ed83a3055d6c1f9fae05f av_one_third  avia-builder-el-239  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-93397e78d45e589287189b5455db6dfc avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/D1KHBByKoqI'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Marie  - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/D1KHBByKoqI?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-241  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-f95456dad6d4c1fe093e336a90c4adbe avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/AdN2zIdfXrs'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Florence - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/AdN2zIdfXrs?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-243  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-60aa12c900bc1994040bebf46dc41613 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/-hVGo1aC6Y8'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Lata  - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/-hVGo1aC6Y8?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-245  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-af240a72e99ed83a3055d6c1f9fae05f\">\n.flex_column.av-gbo69-af240a72e99ed83a3055d6c1f9fae05f{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-af240a72e99ed83a3055d6c1f9fae05f av_one_third  avia-builder-el-246  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-b0651023a682e8d8d938d066d842ccde avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/6oF3_v5-_24'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Nahome - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/6oF3_v5-_24?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-248  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-7a49e1db5ddf285c270928bb8be3a159 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/0Vyu91Mvlf8'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Pauline  - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/0Vyu91Mvlf8?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-250  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-8ea4d5b25612ea58fe4bb60cb47aae4d avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/9o3sm9_tQco'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Amandine - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/9o3sm9_tQco?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-252  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-af240a72e99ed83a3055d6c1f9fae05f\">\n.flex_column.av-gbo69-af240a72e99ed83a3055d6c1f9fae05f{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-af240a72e99ed83a3055d6c1f9fae05f av_one_third  avia-builder-el-253  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-601dab550963b4299d89220f4da84d06 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/Q9tGDZr1m6k'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Julia - Swiss Voice Tour  -  Les Charpentiers , Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/Q9tGDZr1m6k?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-e7ce8bca96597cbb8643f1635ed32554\">\n.flex_column.av-gbo69-e7ce8bca96597cbb8643f1635ed32554{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-e7ce8bca96597cbb8643f1635ed32554 av_one_third  avia-builder-el-255  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-61955e903313d1a16a5b697a110f5233 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/m0VA8Js1WTw'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Lionel - Swiss Voice Tour  -  Les Charpentiers, Morges\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/m0VA8Js1WTw?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-257  el_after_av_one_third  avia-builder-el-last '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":4329,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-5979","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Les Charpentiers - Swiss Voice Tour<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les Charpentiers - Swiss Voice Tour\" \/>\n<meta property=\"og:url\" content=\"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/stagioni-precedenti\/stagione-6\/les-charpentiers\/\" \/>\n<meta property=\"og:site_name\" content=\"Swiss Voice Tour\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-16T12:48:36+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"100 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/stagioni-precedenti\/stagione-6\/les-charpentiers\/\",\"url\":\"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/stagioni-precedenti\/stagione-6\/les-charpentiers\/\",\"name\":\"Les Charpentiers - Swiss Voice Tour\",\"isPartOf\":{\"@id\":\"https:\/\/swissvoicetour.smartfox-adtech.ch\/#website\"},\"datePublished\":\"2020-04-16T09:56:23+00:00\",\"dateModified\":\"2020-04-16T12:48:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/stagioni-precedenti\/stagione-6\/les-charpentiers\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/stagioni-precedenti\/stagione-6\/les-charpentiers\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/stagioni-precedenti\/stagione-6\/les-charpentiers\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stagioni precedenti\",\"item\":\"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/stagioni-precedenti\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Stagione 6\",\"item\":\"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/stagioni-precedenti\/stagione-6\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Les Charpentiers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/swissvoicetour.smartfox-adtech.ch\/#website\",\"url\":\"https:\/\/swissvoicetour.smartfox-adtech.ch\/\",\"name\":\"Swiss Voice Tour\",\"description\":\"Benvenuti nella pagina ufficiale dello Swiss Voice Tour\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/swissvoicetour.smartfox-adtech.ch\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les Charpentiers - Swiss Voice Tour","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"Les Charpentiers - Swiss Voice Tour","og_url":"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/stagioni-precedenti\/stagione-6\/les-charpentiers\/","og_site_name":"Swiss Voice Tour","article_modified_time":"2020-04-16T12:48:36+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"100 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/stagioni-precedenti\/stagione-6\/les-charpentiers\/","url":"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/stagioni-precedenti\/stagione-6\/les-charpentiers\/","name":"Les Charpentiers - Swiss Voice Tour","isPartOf":{"@id":"https:\/\/swissvoicetour.smartfox-adtech.ch\/#website"},"datePublished":"2020-04-16T09:56:23+00:00","dateModified":"2020-04-16T12:48:36+00:00","breadcrumb":{"@id":"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/stagioni-precedenti\/stagione-6\/les-charpentiers\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/stagioni-precedenti\/stagione-6\/les-charpentiers\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/stagioni-precedenti\/stagione-6\/les-charpentiers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/"},{"@type":"ListItem","position":2,"name":"Stagioni precedenti","item":"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/stagioni-precedenti\/"},{"@type":"ListItem","position":3,"name":"Stagione 6","item":"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/stagioni-precedenti\/stagione-6\/"},{"@type":"ListItem","position":4,"name":"Les Charpentiers"}]},{"@type":"WebSite","@id":"https:\/\/swissvoicetour.smartfox-adtech.ch\/#website","url":"https:\/\/swissvoicetour.smartfox-adtech.ch\/","name":"Swiss Voice Tour","description":"Benvenuti nella pagina ufficiale dello Swiss Voice Tour","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/swissvoicetour.smartfox-adtech.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/wp-json\/wp\/v2\/pages\/5979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/wp-json\/wp\/v2\/comments?post=5979"}],"version-history":[{"count":3,"href":"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/wp-json\/wp\/v2\/pages\/5979\/revisions"}],"predecessor-version":[{"id":6293,"href":"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/wp-json\/wp\/v2\/pages\/5979\/revisions\/6293"}],"up":[{"embeddable":true,"href":"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/wp-json\/wp\/v2\/pages\/4329"}],"wp:attachment":[{"href":"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/wp-json\/wp\/v2\/media?parent=5979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}