{"id":4457,"date":"2020-03-31T11:56:44","date_gmt":"2020-03-31T09:56:44","guid":{"rendered":"https:\/\/swissvoicetour.smartfox-adtech.ch\/?page_id=4457"},"modified":"2020-03-31T11:56:45","modified_gmt":"2020-03-31T09:56:45","slug":"oron-arc-en-ciel","status":"publish","type":"page","link":"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/stagioni-precedenti\/stagione-2\/oron-arc-en-ciel\/","title":{"rendered":"Oron Arc-en-ciel"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7m0uc4i-42ab96b437fefc62e751ba5c15e899ea\">\n.avia-section.av-k7m0uc4i-42ab96b437fefc62e751ba5c15e899ea{\nbackground-color:#cca047;\nbackground-image:unset;\n}\n.avia-section.av-k7m0uc4i-42ab96b437fefc62e751ba5c15e899ea .av-extra-border-element .av-extra-border-inner{\nbackground-color:#ffffff;\n}\n<\/style>\n<div id='av_section_1'  class='avia-section av-k7m0uc4i-42ab96b437fefc62e751ba5c15e899ea main_color avia-section-default avia-no-border-styling  avia-builder-el-0  el_before_av_section  avia-builder-el-first  avia-bg-style-scroll av-minimum-height av-minimum-height-custom av-height-custom  container_wrap fullsize'   data-av_minimum_height_px='200'><div class='container av-section-cont-open' style='height:200px'><main  role=\"main\" itemprop=\"mainContentOfPage\"  class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-4457'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k8fq8ioc-7b3b3155ec8f6d57fe16f796d2c5dca8\">\n#top .av-special-heading.av-k8fq8ioc-7b3b3155ec8f6d57fe16f796d2c5dca8{\npadding-bottom:10px;\ncolor:#ffffff;\n}\nbody .av-special-heading.av-k8fq8ioc-7b3b3155ec8f6d57fe16f796d2c5dca8 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-k8fq8ioc-7b3b3155ec8f6d57fe16f796d2c5dca8 .special-heading-inner-border{\nborder-color:#ffffff;\n}\n.av-special-heading.av-k8fq8ioc-7b3b3155ec8f6d57fe16f796d2c5dca8 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-k8fq8ioc-7b3b3155ec8f6d57fe16f796d2c5dca8 av-special-heading-h1 custom-color-heading blockquote modern-quote  avia-builder-el-1  avia-builder-el-no-sibling '><h1 class='av-special-heading-tag '  itemprop=\"headline\"  >Oron Arc-en-ciel<\/h1><div class='av_custom_color av-subheading av-subheading_below'><p>Oron-la-Ville &#8211; Stagione 2<\/p>\n<\/div><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div>\n<\/div><\/div><\/main><!-- close content main element --><\/div><div class='av-extra-border-element border-extra-diagonal border-extra-diagonal-inverse '><div class='av-extra-border-outer'><div class='av-extra-border-inner'><\/div><\/div><\/div><\/div><div id='av_section_2'  class='avia-section av-g1rox-68c6bb8ccff6827f2aa3c50ffa4e4072 main_color avia-section-default avia-no-border-styling  avia-builder-el-2  el_after_av_section  avia-builder-el-last  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-4457'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-bkkg9-a89728ed957b1d9868369d986c5eb249\">\n.flex_column.av-bkkg9-a89728ed957b1d9868369d986c5eb249{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-bkkg9-a89728ed957b1d9868369d986c5eb249 av_one_fifth  avia-builder-el-3  el_before_av_three_fifth  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><div  class='avia-button-wrap av-k7ngtdap-231b8cf340f6a284e87c33287382f842-wrap avia-button-left  avia-builder-el-4  avia-builder-el-no-sibling '><a href='https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/stagioni-precedenti\/stagione-2\/'  class='avia-button av-k7ngtdap-231b8cf340f6a284e87c33287382f842 av-link-btn avia-icon_select-yes-left-icon avia-size-small avia-position-left avia-color-theme-color'   aria-label=\"Stagione 2\"><span class='avia_button_icon avia_button_icon_left' aria-hidden='true' data-av_icon='\ue830' data-av_iconfont='entypo-fontello'><\/span><span class='avia_iconbox_title' >Stagione 2<\/span><\/a><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-bkkg9-d25ce05022cab2ca5ca5d47f01d51633\">\n.flex_column.av-bkkg9-d25ce05022cab2ca5ca5d47f01d51633{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-bkkg9-d25ce05022cab2ca5ca5d47f01d51633 av_three_fifth  avia-builder-el-5  el_after_av_one_fifth  el_before_av_one_fifth  flex_column_div av-zero-column-padding  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k8fq6z6m-7f31b4dd1e61a809f4049d3091e23a4c\">\n#top .av-special-heading.av-k8fq6z6m-7f31b4dd1e61a809f4049d3091e23a4c{\npadding-bottom:20px;\n}\nbody .av-special-heading.av-k8fq6z6m-7f31b4dd1e61a809f4049d3091e23a4c .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-k8fq6z6m-7f31b4dd1e61a809f4049d3091e23a4c .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-k8fq6z6m-7f31b4dd1e61a809f4049d3091e23a4c av-special-heading-h2 blockquote modern-quote modern-centered  avia-builder-el-6  el_before_av_video  avia-builder-el-first '><h2 class='av-special-heading-tag '  itemprop=\"headline\"  >IL MEGLIO DELLA FINALE SU VIDEO<\/h2><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n<div  class='avia-video av-k7nga4og-6fc97a4436b3fb8e5ddf677d25ea7874 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/1agppTwJQ6U'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Kids Voice Tour 2015 - Finale Oron Arc-en-Ciel\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/1agppTwJQ6U?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-bkkg9-d25ce05022cab2ca5ca5d47f01d51633\">\n.flex_column.av-bkkg9-d25ce05022cab2ca5ca5d47f01d51633{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-bkkg9-d25ce05022cab2ca5ca5d47f01d51633 av_one_fifth  avia-builder-el-8  el_after_av_three_fifth  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-9  el_after_av_one_fifth  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-af240a72e99ed83a3055d6c1f9fae05f\">\n.flex_column.av-gbo69-af240a72e99ed83a3055d6c1f9fae05f{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-af240a72e99ed83a3055d6c1f9fae05f av_one_third  avia-builder-el-10  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-669baef8fc9cbc73227ca787adc276f3 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/u1XKgcJstEs'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Tia - Kids Voice Tour - Oron Arc-en-Ciel\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/u1XKgcJstEs?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-parch-9cd4ff22856a600593141d0b4664c792\">\n.flex_column.av-parch-9cd4ff22856a600593141d0b4664c792{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-parch-9cd4ff22856a600593141d0b4664c792 av_one_third  avia-builder-el-12  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-fa9caf1d850d60713299dff957dff7b2 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/9pen8oJzyWQ'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Ana Rita - Kids Voice Tour - Oro Arc-en-Ciel\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/9pen8oJzyWQ?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-jqgp5-dbe27e73b814f2d082cf1d3f6d25ccb5\">\n.flex_column.av-jqgp5-dbe27e73b814f2d082cf1d3f6d25ccb5{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-jqgp5-dbe27e73b814f2d082cf1d3f6d25ccb5 av_one_third  avia-builder-el-14  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-7943feda6ce90dd2a0b4329f8c126a3b avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/IcGvsewBkRs'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Chloe\u0301 - Kids Voice Tour - Oron Arc-en-Ciel\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/IcGvsewBkRs?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-16  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-1a8e20dfd422795adb994ee0f189fcf9\">\n.flex_column.av-747ax-1a8e20dfd422795adb994ee0f189fcf9{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-1a8e20dfd422795adb994ee0f189fcf9 av_one_third  avia-builder-el-17  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-d2144ec4b46bf0b9906e5b8a07b7ccc3 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/DbZkqpFO6L8 '><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Lena - Kids Voice Tour - Oron Arc-en-Ciel\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/DbZkqpFO6L8?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-46f8cd06e9d3175d0940f18947d5d919\">\n.flex_column.av-747ax-46f8cd06e9d3175d0940f18947d5d919{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-46f8cd06e9d3175d0940f18947d5d919 av_one_third  avia-builder-el-19  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-cf7c812ca42a51f43d9f084d4dbd960c avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url=' https:\/\/youtu.be\/hZjH8FpT584'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Estelle - Kids Voice Tour - Oron Arc-en-Ciel\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/hZjH8FpT584?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-46f8cd06e9d3175d0940f18947d5d919\">\n.flex_column.av-747ax-46f8cd06e9d3175d0940f18947d5d919{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-46f8cd06e9d3175d0940f18947d5d919 av_one_third  avia-builder-el-21  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-8bd59a73be526360cfe0395f1e275261 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/TUBqNYvNNPw'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Sara - Kids Voice Tour - Oron Arc-en-Ciel\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/TUBqNYvNNPw?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-23  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-1a8e20dfd422795adb994ee0f189fcf9\">\n.flex_column.av-747ax-1a8e20dfd422795adb994ee0f189fcf9{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-1a8e20dfd422795adb994ee0f189fcf9 av_one_third  avia-builder-el-24  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-a539693a771765d06724c9e68280979e avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/Aryqz1XlAbI'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Marilyne - Kids Voice Tour - Oron Arc-en-Ciel\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/Aryqz1XlAbI?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-46f8cd06e9d3175d0940f18947d5d919\">\n.flex_column.av-747ax-46f8cd06e9d3175d0940f18947d5d919{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-46f8cd06e9d3175d0940f18947d5d919 av_one_third  avia-builder-el-26  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-365a4013f8885fe2ea44e0f6078943ac avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/flzw8Fj4gFU'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Sophia - Kids Voice Tour - Oron Arc-en-Ciel\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/flzw8Fj4gFU?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-46f8cd06e9d3175d0940f18947d5d919\">\n.flex_column.av-747ax-46f8cd06e9d3175d0940f18947d5d919{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-46f8cd06e9d3175d0940f18947d5d919 av_one_third  avia-builder-el-28  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-721654e5241293a0dfe736bb18430634 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/LlywONGTLu4'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Marion - Kids Voice Tour - Oron Arc-en-Ciel\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/LlywONGTLu4?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-30  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-1a8e20dfd422795adb994ee0f189fcf9\">\n.flex_column.av-747ax-1a8e20dfd422795adb994ee0f189fcf9{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-1a8e20dfd422795adb994ee0f189fcf9 av_one_third  avia-builder-el-31  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-371bdc025c56d723ce65ef16a318f42d avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/k1mj635tR2Y'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Anastacia - Kids Voice Tour - Oron Arc-en-Ciel\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/k1mj635tR2Y?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-46f8cd06e9d3175d0940f18947d5d919\">\n.flex_column.av-747ax-46f8cd06e9d3175d0940f18947d5d919{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-46f8cd06e9d3175d0940f18947d5d919 av_one_third  avia-builder-el-33  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-80674f51a3fea68756a7fde66b7dba36 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/TGTlXsThhYE'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Lily - Kids Voice Tour - Oron Arc-en-Ciel\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/TGTlXsThhYE?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-46f8cd06e9d3175d0940f18947d5d919\">\n.flex_column.av-747ax-46f8cd06e9d3175d0940f18947d5d919{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-46f8cd06e9d3175d0940f18947d5d919 av_one_third  avia-builder-el-35  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-e7dad5393c6a14de29dca89e7d16fc9a avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/ys136KGEjRA'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Marie - Kids Voice Tour - Oron Arc-en-Ciel\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/ys136KGEjRA?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-37  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-1a8e20dfd422795adb994ee0f189fcf9\">\n.flex_column.av-747ax-1a8e20dfd422795adb994ee0f189fcf9{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-1a8e20dfd422795adb994ee0f189fcf9 av_one_third  avia-builder-el-38  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-8c4d9048fc82b77486a4206f099b4187 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/SSeCpXbujho'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Isaline - Kids Voice Tour - Oron Arc-en-Ciel\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/SSeCpXbujho?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-46f8cd06e9d3175d0940f18947d5d919\">\n.flex_column.av-747ax-46f8cd06e9d3175d0940f18947d5d919{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-46f8cd06e9d3175d0940f18947d5d919 av_one_third  avia-builder-el-40  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-704d667bff3eed1186be9716080c249c avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/tpMRiOiiZFE'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Alexa - Kids Voice Tour - Oron Arc-en-Ciel\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/tpMRiOiiZFE?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-46f8cd06e9d3175d0940f18947d5d919\">\n.flex_column.av-747ax-46f8cd06e9d3175d0940f18947d5d919{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-46f8cd06e9d3175d0940f18947d5d919 av_one_third  avia-builder-el-42  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-7e522012db2e567876b08a2881b47f06 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/0ABbtoPfDJg'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Ivana - Kids Voice Tour - Oron Arc-en-Ciel\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/0ABbtoPfDJg?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-44  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-1a8e20dfd422795adb994ee0f189fcf9\">\n.flex_column.av-747ax-1a8e20dfd422795adb994ee0f189fcf9{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-1a8e20dfd422795adb994ee0f189fcf9 av_one_third  avia-builder-el-45  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-0a0cbc1ddbfb1cd133fae48ad29e6fe5 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/n1lYq1ClPkw'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Laeticia - Kids Voice Tour - Oron Arc-en-Ciel\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/n1lYq1ClPkw?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-46f8cd06e9d3175d0940f18947d5d919\">\n.flex_column.av-747ax-46f8cd06e9d3175d0940f18947d5d919{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-46f8cd06e9d3175d0940f18947d5d919 av_one_third  avia-builder-el-47  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-7d6b71478a07ae22ef8ff0d5ac70594c avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/B4NMsKyl7js'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Alexia - Kids Voice Tour - Oron Arc-en-Ciel\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/B4NMsKyl7js?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-46f8cd06e9d3175d0940f18947d5d919\">\n.flex_column.av-747ax-46f8cd06e9d3175d0940f18947d5d919{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-46f8cd06e9d3175d0940f18947d5d919 av_one_third  avia-builder-el-49  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-a0c5563ea4f2f4e6ece2145bae6d948d avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/YU11lzRJJ5k'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Elisa - Kids Voice Tour  - Oron Arc-en-Ciel\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/YU11lzRJJ5k?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-51  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-1a8e20dfd422795adb994ee0f189fcf9\">\n.flex_column.av-747ax-1a8e20dfd422795adb994ee0f189fcf9{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-1a8e20dfd422795adb994ee0f189fcf9 av_one_third  avia-builder-el-52  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-e79ff23b3bb417f6fe0f077164dffde3 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/_-NZiz4ecUA'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Ashley - Kids Voice Tour - Oron Arc-en-Ciel\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/_-NZiz4ecUA?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-46f8cd06e9d3175d0940f18947d5d919\">\n.flex_column.av-747ax-46f8cd06e9d3175d0940f18947d5d919{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-46f8cd06e9d3175d0940f18947d5d919 av_one_third  avia-builder-el-54  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-9f1fdea9eeae1b3f1a4d6692c90ec10b avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/3IBZ0_B58A4 '><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Me\u0301lodie - Kids Voice Tour - Oron Arc-en-Ciel\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/3IBZ0_B58A4?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-46f8cd06e9d3175d0940f18947d5d919\">\n.flex_column.av-747ax-46f8cd06e9d3175d0940f18947d5d919{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-46f8cd06e9d3175d0940f18947d5d919 av_one_third  avia-builder-el-56  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-c073b020e3b237583cdb7b1fe0870f94 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/tCHo0filEEM'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Be\u0301atrice - Kids Voice Tour - Oron Arc-en-Ciel\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/tCHo0filEEM?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-58  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-1a8e20dfd422795adb994ee0f189fcf9\">\n.flex_column.av-747ax-1a8e20dfd422795adb994ee0f189fcf9{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-1a8e20dfd422795adb994ee0f189fcf9 av_one_third  avia-builder-el-59  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-50114b8acd0199334a3962d442af4bc9 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/Uxg6al366-g'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Lola - Kids Voice Tour - Oron Arc-en-Ciel\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/Uxg6al366-g?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-46f8cd06e9d3175d0940f18947d5d919\">\n.flex_column.av-747ax-46f8cd06e9d3175d0940f18947d5d919{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-46f8cd06e9d3175d0940f18947d5d919 av_one_third  avia-builder-el-61  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-bc00b6ef084278a518955cd8d3a68d50 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/SaJsIz39zWc'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Alize\u0301e - Kids Voice Tour - Oron Arc-en-Ciel\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/SaJsIz39zWc?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-46f8cd06e9d3175d0940f18947d5d919\">\n.flex_column.av-747ax-46f8cd06e9d3175d0940f18947d5d919{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-46f8cd06e9d3175d0940f18947d5d919 av_one_third  avia-builder-el-63  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-0de85da91899236c34894f960d2ad028 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/L9PMXB_0Nxk'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Le\u0301o - Kids Voice Tour - Oron Arc-en-Ciel\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/L9PMXB_0Nxk?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-65  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-1a8e20dfd422795adb994ee0f189fcf9\">\n.flex_column.av-747ax-1a8e20dfd422795adb994ee0f189fcf9{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-1a8e20dfd422795adb994ee0f189fcf9 av_one_third  avia-builder-el-66  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-9f372755133073c29edfdae52975fa6a avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/jUkWPL68vqQ'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Salome\u0301 - Kids Voice Tour - Oron Arc-en-Ciel\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/jUkWPL68vqQ?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-46f8cd06e9d3175d0940f18947d5d919\">\n.flex_column.av-747ax-46f8cd06e9d3175d0940f18947d5d919{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-46f8cd06e9d3175d0940f18947d5d919 av_one_third  avia-builder-el-68  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-6a62a9d92ce9fed3cfee0705ac16afd8 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/gMXHd2sZpKk'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Amanda - Kids Voice Tour - Oron Arc-en-Ciel\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/gMXHd2sZpKk?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-46f8cd06e9d3175d0940f18947d5d919\">\n.flex_column.av-747ax-46f8cd06e9d3175d0940f18947d5d919{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-46f8cd06e9d3175d0940f18947d5d919 av_one_third  avia-builder-el-70  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-d7a5e5e07f426764be64aca0df5168cf avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/_Uce9cdfM04'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Kim - Kids Voice Tour - Oron Arc-en-Ciel\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/_Uce9cdfM04?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-72  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-1a8e20dfd422795adb994ee0f189fcf9\">\n.flex_column.av-747ax-1a8e20dfd422795adb994ee0f189fcf9{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-1a8e20dfd422795adb994ee0f189fcf9 av_one_third  avia-builder-el-73  el_after_av_hr  avia-builder-el-last  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-873bc7a8c221a11cfded9c35c9ccc2f7 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/rOR0BBCVU_E '><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Jessica - Kids Voice Tour - Oron Arc en Ciel\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/rOR0BBCVU_E?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":4325,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-4457","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Oron Arc-en-ciel - Swiss Voice Tour<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oron Arc-en-ciel - Swiss Voice Tour\" \/>\n<meta property=\"og:url\" content=\"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/stagioni-precedenti\/stagione-2\/oron-arc-en-ciel\/\" \/>\n<meta property=\"og:site_name\" content=\"Swiss Voice Tour\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-31T09:56:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"30 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/stagioni-precedenti\/stagione-2\/oron-arc-en-ciel\/\",\"url\":\"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/stagioni-precedenti\/stagione-2\/oron-arc-en-ciel\/\",\"name\":\"Oron Arc-en-ciel - Swiss Voice Tour\",\"isPartOf\":{\"@id\":\"https:\/\/swissvoicetour.smartfox-adtech.ch\/#website\"},\"datePublished\":\"2020-03-31T09:56:44+00:00\",\"dateModified\":\"2020-03-31T09:56:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/stagioni-precedenti\/stagione-2\/oron-arc-en-ciel\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/stagioni-precedenti\/stagione-2\/oron-arc-en-ciel\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/stagioni-precedenti\/stagione-2\/oron-arc-en-ciel\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stagioni precedenti\",\"item\":\"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/stagioni-precedenti\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Stagione 2\",\"item\":\"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/stagioni-precedenti\/stagione-2\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Oron Arc-en-ciel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/swissvoicetour.smartfox-adtech.ch\/#website\",\"url\":\"https:\/\/swissvoicetour.smartfox-adtech.ch\/\",\"name\":\"Swiss Voice Tour\",\"description\":\"Benvenuti nella pagina ufficiale dello Swiss Voice Tour\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/swissvoicetour.smartfox-adtech.ch\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Oron Arc-en-ciel - Swiss Voice Tour","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"Oron Arc-en-ciel - Swiss Voice Tour","og_url":"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/stagioni-precedenti\/stagione-2\/oron-arc-en-ciel\/","og_site_name":"Swiss Voice Tour","article_modified_time":"2020-03-31T09:56:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"30 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/stagioni-precedenti\/stagione-2\/oron-arc-en-ciel\/","url":"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/stagioni-precedenti\/stagione-2\/oron-arc-en-ciel\/","name":"Oron Arc-en-ciel - Swiss Voice Tour","isPartOf":{"@id":"https:\/\/swissvoicetour.smartfox-adtech.ch\/#website"},"datePublished":"2020-03-31T09:56:44+00:00","dateModified":"2020-03-31T09:56:45+00:00","breadcrumb":{"@id":"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/stagioni-precedenti\/stagione-2\/oron-arc-en-ciel\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/stagioni-precedenti\/stagione-2\/oron-arc-en-ciel\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/stagioni-precedenti\/stagione-2\/oron-arc-en-ciel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/"},{"@type":"ListItem","position":2,"name":"Stagioni precedenti","item":"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/stagioni-precedenti\/"},{"@type":"ListItem","position":3,"name":"Stagione 2","item":"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/stagioni-precedenti\/stagione-2\/"},{"@type":"ListItem","position":4,"name":"Oron Arc-en-ciel"}]},{"@type":"WebSite","@id":"https:\/\/swissvoicetour.smartfox-adtech.ch\/#website","url":"https:\/\/swissvoicetour.smartfox-adtech.ch\/","name":"Swiss Voice Tour","description":"Benvenuti nella pagina ufficiale dello Swiss Voice Tour","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/swissvoicetour.smartfox-adtech.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/wp-json\/wp\/v2\/pages\/4457","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/wp-json\/wp\/v2\/comments?post=4457"}],"version-history":[{"count":2,"href":"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/wp-json\/wp\/v2\/pages\/4457\/revisions"}],"predecessor-version":[{"id":4469,"href":"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/wp-json\/wp\/v2\/pages\/4457\/revisions\/4469"}],"up":[{"embeddable":true,"href":"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/wp-json\/wp\/v2\/pages\/4325"}],"wp:attachment":[{"href":"https:\/\/swissvoicetour.smartfox-adtech.ch\/it\/wp-json\/wp\/v2\/media?parent=4457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}