{"id":6070,"date":"2020-04-16T12:06:37","date_gmt":"2020-04-16T10:06:37","guid":{"rendered":"https:\/\/swissvoicetour.smartfox-adtech.ch\/?page_id=6070"},"modified":"2020-04-16T14:59:50","modified_gmt":"2020-04-16T12:59:50","slug":"taegipark-kids","status":"publish","type":"page","link":"https:\/\/swissvoicetour.smartfox-adtech.ch\/de\/staffeln\/staffel-6\/taegipark-kids\/","title":{"rendered":"T\u00c4GIPARK &#8211; Kids"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7m0uc4i-42ab96b437fefc62e751ba5c15e899ea\">\n.avia-section.av-k7m0uc4i-42ab96b437fefc62e751ba5c15e899ea{\nbackground-color:#cca047;\nbackground-image:unset;\n}\n.avia-section.av-k7m0uc4i-42ab96b437fefc62e751ba5c15e899ea .av-extra-border-element .av-extra-border-inner{\nbackground-color:#ffffff;\n}\n<\/style>\n<div id='av_section_1'  class='avia-section av-k7m0uc4i-42ab96b437fefc62e751ba5c15e899ea main_color avia-section-default avia-no-border-styling  avia-builder-el-0  el_before_av_section  avia-builder-el-first  avia-bg-style-scroll av-minimum-height av-minimum-height-custom av-height-custom  container_wrap fullsize'   data-av_minimum_height_px='200'><div class='container av-section-cont-open' style='height:200px'><main  role=\"main\" itemprop=\"mainContentOfPage\"  class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-6070'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k92txvko-cf5b6c21a87ee060d27f91879bb78d17\">\n#top .av-special-heading.av-k92txvko-cf5b6c21a87ee060d27f91879bb78d17{\npadding-bottom:10px;\ncolor:#ffffff;\n}\nbody .av-special-heading.av-k92txvko-cf5b6c21a87ee060d27f91879bb78d17 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-k92txvko-cf5b6c21a87ee060d27f91879bb78d17 .special-heading-inner-border{\nborder-color:#ffffff;\n}\n.av-special-heading.av-k92txvko-cf5b6c21a87ee060d27f91879bb78d17 .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  class='av-special-heading av-k92txvko-cf5b6c21a87ee060d27f91879bb78d17 av-special-heading-h1 custom-color-heading blockquote modern-quote  avia-builder-el-1  avia-builder-el-no-sibling '><h1 class='av-special-heading-tag '  itemprop=\"headline\"  >T\u00c4GIPARK &#8211; Kids Voice Tour <\/h1><div class='av_custom_color av-subheading av-subheading_below'><p>WETTINGEN &#8211; Staffel 6<\/p>\n<\/div><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div>\n<\/div><\/div><\/main><!-- close content main element --><\/div><div class='av-extra-border-element border-extra-diagonal border-extra-diagonal-inverse '><div class='av-extra-border-outer'><div class='av-extra-border-inner'><\/div><\/div><\/div><\/div><div id='av_section_2'  class='avia-section av-g1rox-68c6bb8ccff6827f2aa3c50ffa4e4072 main_color avia-section-default avia-no-border-styling  avia-builder-el-2  el_after_av_section  avia-builder-el-last  avia-bg-style-scroll container_wrap fullsize'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-full alpha units'><div class='post-entry post-entry-type-page post-entry-6070'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-bkkg9-a89728ed957b1d9868369d986c5eb249\">\n.flex_column.av-bkkg9-a89728ed957b1d9868369d986c5eb249{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-bkkg9-a89728ed957b1d9868369d986c5eb249 av_one_fifth  avia-builder-el-3  el_before_av_three_fifth  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><div  class='avia-button-wrap av-k7ngtdap-5a55cbc5523d1274b08522b258c71d78-wrap avia-button-left  avia-builder-el-4  avia-builder-el-no-sibling '><a href='https:\/\/swissvoicetour.smartfox-adtech.ch\/de\/staffeln\/staffel-6\/'  class='avia-button av-k7ngtdap-5a55cbc5523d1274b08522b258c71d78 av-link-btn avia-icon_select-yes-left-icon avia-size-small avia-position-left avia-color-theme-color'   aria-label=\"Staffel 6\"><span class='avia_button_icon avia_button_icon_left' aria-hidden='true' data-av_icon='\ue830' data-av_iconfont='entypo-fontello'><\/span><span class='avia_iconbox_title' >Staffel 6<\/span><\/a><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-bkkg9-d25ce05022cab2ca5ca5d47f01d51633\">\n.flex_column.av-bkkg9-d25ce05022cab2ca5ca5d47f01d51633{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-bkkg9-d25ce05022cab2ca5ca5d47f01d51633 av_three_fifth  avia-builder-el-5  el_after_av_one_fifth  el_before_av_one_fifth  flex_column_div av-zero-column-padding  '     ><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-bkkg9-d25ce05022cab2ca5ca5d47f01d51633\">\n.flex_column.av-bkkg9-d25ce05022cab2ca5ca5d47f01d51633{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-bkkg9-d25ce05022cab2ca5ca5d47f01d51633 av_one_fifth  avia-builder-el-6  el_after_av_three_fifth  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-7  el_after_av_one_fifth  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gbo69-af240a72e99ed83a3055d6c1f9fae05f\">\n.flex_column.av-gbo69-af240a72e99ed83a3055d6c1f9fae05f{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gbo69-af240a72e99ed83a3055d6c1f9fae05f av_one_third  avia-builder-el-8  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-3108b4d74df217c42fdbfa857d617332 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/_LPONEqCd0M'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Nazik 9 ans  - Swiss Voice Tour 2019 - Ta\u0308gipark , Wettingen\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/_LPONEqCd0M?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-parch-9cd4ff22856a600593141d0b4664c792\">\n.flex_column.av-parch-9cd4ff22856a600593141d0b4664c792{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-parch-9cd4ff22856a600593141d0b4664c792 av_one_third  avia-builder-el-10  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-75061759d42378ceaf4efcb421d079a1 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/Q8-8lquOTqE'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Sina 15 ans Swiss Voice Tour 2019 - Ta\u0308gipark , Wettingen\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/Q8-8lquOTqE?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-jqgp5-dbe27e73b814f2d082cf1d3f6d25ccb5\">\n.flex_column.av-jqgp5-dbe27e73b814f2d082cf1d3f6d25ccb5{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-jqgp5-dbe27e73b814f2d082cf1d3f6d25ccb5 av_one_third  avia-builder-el-12  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-55acbc83697e22b75f1346a72a8fd2f7 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/UVgsrAoLaik'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Natasha 11 ans - Swiss Voice Tour 2019 - Ta\u0308gipark , Wettingen\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/UVgsrAoLaik?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-14  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-1a8e20dfd422795adb994ee0f189fcf9\">\n.flex_column.av-747ax-1a8e20dfd422795adb994ee0f189fcf9{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-1a8e20dfd422795adb994ee0f189fcf9 av_one_third  avia-builder-el-15  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-d18c12e760400be06ea218d832cec8d4 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/GyaJEYotM50'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Lisa 16 ans - Swiss Voice Tour 2019 - Ta\u0308gipark , Wettingen\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/GyaJEYotM50?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-46f8cd06e9d3175d0940f18947d5d919\">\n.flex_column.av-747ax-46f8cd06e9d3175d0940f18947d5d919{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-46f8cd06e9d3175d0940f18947d5d919 av_one_third  avia-builder-el-17  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-f41c4c915a0288f4bd698fa9ea67e570 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/VBg2YxWUQVc'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Tej 13 ans  - Swiss Voice Tour 2019 - Ta\u0308gipark , Wettingen\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/VBg2YxWUQVc?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-46f8cd06e9d3175d0940f18947d5d919\">\n.flex_column.av-747ax-46f8cd06e9d3175d0940f18947d5d919{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-46f8cd06e9d3175d0940f18947d5d919 av_one_third  avia-builder-el-19  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-672039f3d6d91828940fb97ac76fc567 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/LSroeAK6kpk'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Taisija 15 ans  - Swiss Voice Tour 2019 - Ta\u0308gipark , Wettingen\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/LSroeAK6kpk?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-21  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-1a8e20dfd422795adb994ee0f189fcf9\">\n.flex_column.av-747ax-1a8e20dfd422795adb994ee0f189fcf9{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-1a8e20dfd422795adb994ee0f189fcf9 av_one_third  avia-builder-el-22  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-aba7131059c8225eaad52bcfe35e47b4 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/ADPV6SdSqGw'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Olivia 13 ans - Swiss Voice Tour 2019 - Ta\u0308gipark , Wettingen\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/ADPV6SdSqGw?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-46f8cd06e9d3175d0940f18947d5d919\">\n.flex_column.av-747ax-46f8cd06e9d3175d0940f18947d5d919{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-46f8cd06e9d3175d0940f18947d5d919 av_one_third  avia-builder-el-24  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-7953e4ff6159493b5a824b9770c0a07b avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/kLz41Os47jw'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Alexander 12 ans - Swiss Voice Tour 2019 - Ta\u0308gipark , Wettingen\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/kLz41Os47jw?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-46f8cd06e9d3175d0940f18947d5d919\">\n.flex_column.av-747ax-46f8cd06e9d3175d0940f18947d5d919{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-46f8cd06e9d3175d0940f18947d5d919 av_one_third  avia-builder-el-26  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-c9dd3c87e0f3947a762aa11ca366ca33 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/emBrmSlK_YU'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Francesco 16 ans - Swiss Voice Tour 2019 - Ta\u0308gipark , Wettingen\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/emBrmSlK_YU?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-28  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-1a8e20dfd422795adb994ee0f189fcf9\">\n.flex_column.av-747ax-1a8e20dfd422795adb994ee0f189fcf9{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-1a8e20dfd422795adb994ee0f189fcf9 av_one_third  avia-builder-el-29  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-77637141d510d4e4c079bb100648a0f1 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/DMYzCAbcg4Y'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Jessica 16 ans- Swiss Voice Tour 2019 - Ta\u0308gipark , Wettingen 110\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/DMYzCAbcg4Y?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-46f8cd06e9d3175d0940f18947d5d919\">\n.flex_column.av-747ax-46f8cd06e9d3175d0940f18947d5d919{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-46f8cd06e9d3175d0940f18947d5d919 av_one_third  avia-builder-el-31  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-0ea5dff814205d992c4fc22db080d87e avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/hP1UMevd4ys'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Marienne 16 ans - Swiss Voice Tour 2019 - Ta\u0308gipark , Wettingen\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/hP1UMevd4ys?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-46f8cd06e9d3175d0940f18947d5d919\">\n.flex_column.av-747ax-46f8cd06e9d3175d0940f18947d5d919{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-46f8cd06e9d3175d0940f18947d5d919 av_one_third  avia-builder-el-33  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-484065a14833343b66a9157145b9e66c avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/FqP7_16yxfw'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Moana 16 ans  - Swiss Voice Tour 2019 - Ta\u0308gipark , Wettingen\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/FqP7_16yxfw?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-35  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-1a8e20dfd422795adb994ee0f189fcf9\">\n.flex_column.av-747ax-1a8e20dfd422795adb994ee0f189fcf9{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-1a8e20dfd422795adb994ee0f189fcf9 av_one_third  avia-builder-el-36  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-07fd1693de568990592fd041e416bef2 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/o6UgPhubrVQ'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Marisa 15 ans - Swiss Voice Tour 2019 - Ta\u0308gipark , Wettingen\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/o6UgPhubrVQ?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-46f8cd06e9d3175d0940f18947d5d919\">\n.flex_column.av-747ax-46f8cd06e9d3175d0940f18947d5d919{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-46f8cd06e9d3175d0940f18947d5d919 av_one_third  avia-builder-el-38  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-ef4fcc3e34193ad2ae831acb11185c8c avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/zXt_narWIy8'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Nadalina 9 ans  - Swiss Voice Tour 2019 - T\u00e4gipark , Wettingen\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/zXt_narWIy8?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-46f8cd06e9d3175d0940f18947d5d919\">\n.flex_column.av-747ax-46f8cd06e9d3175d0940f18947d5d919{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-46f8cd06e9d3175d0940f18947d5d919 av_one_third  avia-builder-el-40  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-bfe5e4a1a7bc4d3e7430e40605ff13d1 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/IJ82wZk5VMA'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Justin 14ans  - Swiss Voice Tour 2019 - T\u00e4gipark , Wettingen\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/IJ82wZk5VMA?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-42  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-1a8e20dfd422795adb994ee0f189fcf9\">\n.flex_column.av-747ax-1a8e20dfd422795adb994ee0f189fcf9{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-1a8e20dfd422795adb994ee0f189fcf9 av_one_third  avia-builder-el-43  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-483953fc99b53e050246f65e06b53e28 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/V6KH7pkeLuY'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Emily 11 ans - Swiss Voice Tour 2019 - T\u00e4gipark , Wettingen\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/V6KH7pkeLuY?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-46f8cd06e9d3175d0940f18947d5d919\">\n.flex_column.av-747ax-46f8cd06e9d3175d0940f18947d5d919{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-46f8cd06e9d3175d0940f18947d5d919 av_one_third  avia-builder-el-45  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-2f1b359ec9e7a386516895d155729152 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/o4FSnBJAcpY'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Avrora. 14 ans - Swiss Voice Tour 2019 - T\u00e4gipark , Wettingen\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/o4FSnBJAcpY?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-46f8cd06e9d3175d0940f18947d5d919\">\n.flex_column.av-747ax-46f8cd06e9d3175d0940f18947d5d919{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-46f8cd06e9d3175d0940f18947d5d919 av_one_third  avia-builder-el-47  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-385d3aabf70d0ed7e97b89b5fc68b809 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/Ahj0WO2HU18'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Sarah 15ans  - Swiss Voice Tour 2019 - T\u00e4gipark , Wettingen\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/Ahj0WO2HU18?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-49  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-1a8e20dfd422795adb994ee0f189fcf9\">\n.flex_column.av-747ax-1a8e20dfd422795adb994ee0f189fcf9{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-1a8e20dfd422795adb994ee0f189fcf9 av_one_third  avia-builder-el-50  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-52ed52081c0457aaf6e9f141a00086ba avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/Qw5RoykW01M'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Dennis 13ans   - Swiss Voice Tour 2019 - T\u00e4gipark , Wettingen\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/Qw5RoykW01M?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-46f8cd06e9d3175d0940f18947d5d919\">\n.flex_column.av-747ax-46f8cd06e9d3175d0940f18947d5d919{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-46f8cd06e9d3175d0940f18947d5d919 av_one_third  avia-builder-el-52  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-c26081d9d1de1544967ce1bb5abeae6c avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/Kq7wkgddlQs'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Shruthi  10ans  - Swiss Voice Tour 2019 - T\u00e4gipark , Wettingen\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/Kq7wkgddlQs?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-46f8cd06e9d3175d0940f18947d5d919\">\n.flex_column.av-747ax-46f8cd06e9d3175d0940f18947d5d919{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-46f8cd06e9d3175d0940f18947d5d919 av_one_third  avia-builder-el-54  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-847bb28f70b5fd826b005d4abb27652f avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/vhOe7V5zdvU'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Leya 14 ans - Swiss Voice Tour 2019 - T\u00e4gipark , Wettingen\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/vhOe7V5zdvU?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-56  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-1a8e20dfd422795adb994ee0f189fcf9\">\n.flex_column.av-747ax-1a8e20dfd422795adb994ee0f189fcf9{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-1a8e20dfd422795adb994ee0f189fcf9 av_one_third  avia-builder-el-57  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-1792914ae485c2cc5dd3061807a4a8f7 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/NVakFUeh07c'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Thilda  14ans - Swiss Voice Tour 2019 - T\u00e4gipark , Wettingen\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/NVakFUeh07c?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-46f8cd06e9d3175d0940f18947d5d919\">\n.flex_column.av-747ax-46f8cd06e9d3175d0940f18947d5d919{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-46f8cd06e9d3175d0940f18947d5d919 av_one_third  avia-builder-el-59  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-72fc468f4cc2dfee904abda797ae306f avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/xB0Y7AwyMFI'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Bill Daniel  10ans- Swiss Voice Tour 2019 - T\u00e4gipark , Wettingen\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/xB0Y7AwyMFI?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-46f8cd06e9d3175d0940f18947d5d919\">\n.flex_column.av-747ax-46f8cd06e9d3175d0940f18947d5d919{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-46f8cd06e9d3175d0940f18947d5d919 av_one_third  avia-builder-el-61  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-4f80002b456fff41f4c8eea3b632c6f3 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/yOZfNGefcdg'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Sophie  9ans  - Swiss Voice Tour 2019 - T\u00e4gipark , Wettingen\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/yOZfNGefcdg?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-63  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-1a8e20dfd422795adb994ee0f189fcf9\">\n.flex_column.av-747ax-1a8e20dfd422795adb994ee0f189fcf9{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-1a8e20dfd422795adb994ee0f189fcf9 av_one_third  avia-builder-el-64  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-c2263bbe8269eaa9688ade3f963207bd avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/1MSxE5mfzGw'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Elisaveta  9ans - Swiss Voice Tour 2019 - T\u00e4gipark , Wettingen\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/1MSxE5mfzGw?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-46f8cd06e9d3175d0940f18947d5d919\">\n.flex_column.av-747ax-46f8cd06e9d3175d0940f18947d5d919{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-46f8cd06e9d3175d0940f18947d5d919 av_one_third  avia-builder-el-66  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-0146bbed3163d2112d15896adedbfff0 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/jzPHuL_84Nw'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Ioan. 12ans- Swiss Voice Tour 2019 - T\u00e4gipark , Wettingen\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/jzPHuL_84Nw?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-46f8cd06e9d3175d0940f18947d5d919\">\n.flex_column.av-747ax-46f8cd06e9d3175d0940f18947d5d919{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-46f8cd06e9d3175d0940f18947d5d919 av_one_third  avia-builder-el-68  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-4e23d8f453993d2487d74daf99a80583 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/FhsLa2lVIEo'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Livia  14ans - Swiss Voice Tour 2019 - T\u00e4gipark , Wettingen\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/FhsLa2lVIEo?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-70  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-1a8e20dfd422795adb994ee0f189fcf9\">\n.flex_column.av-747ax-1a8e20dfd422795adb994ee0f189fcf9{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-1a8e20dfd422795adb994ee0f189fcf9 av_one_third  avia-builder-el-71  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-30c17bd4a7b94621d6a821b0d3a880ff avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/H-iCe0Bcquk'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Samira  14ans  - Swiss Voice Tour 2019 - Ta\u0308gipark , Wettingen\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/H-iCe0Bcquk?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-46f8cd06e9d3175d0940f18947d5d919\">\n.flex_column.av-747ax-46f8cd06e9d3175d0940f18947d5d919{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-46f8cd06e9d3175d0940f18947d5d919 av_one_third  avia-builder-el-73  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-5ec0e1258210d2d42a1387bf2c85b29a avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/F98gWstwlgU'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Aurela . 12ans - Swiss Voice Tour 2019 - Ta\u0308gipark , Wettingen\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/F98gWstwlgU?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-46f8cd06e9d3175d0940f18947d5d919\">\n.flex_column.av-747ax-46f8cd06e9d3175d0940f18947d5d919{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-46f8cd06e9d3175d0940f18947d5d919 av_one_third  avia-builder-el-75  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-a2485aa904e1dc8a60db9a1d10576b10 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/0iMIpMzXaZQ'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Madalena  12ans   - Swiss Voice Tour 2019 - Ta\u0308gipark , Wettingen\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/0iMIpMzXaZQ?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-77  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-1a8e20dfd422795adb994ee0f189fcf9\">\n.flex_column.av-747ax-1a8e20dfd422795adb994ee0f189fcf9{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-1a8e20dfd422795adb994ee0f189fcf9 av_one_third  avia-builder-el-78  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-5b57b22900718dfd04830dd900bbbd85 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/Ve_TXnAIBvk'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Lara  11 ans &amp; Vanessa 13ans   - Swiss Voice Tour 2019 - Ta\u0308gipark , Wettingen\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/Ve_TXnAIBvk?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-46f8cd06e9d3175d0940f18947d5d919\">\n.flex_column.av-747ax-46f8cd06e9d3175d0940f18947d5d919{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-46f8cd06e9d3175d0940f18947d5d919 av_one_third  avia-builder-el-80  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-680f5d0dca08b908580bd21bc70b4fc7 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/2qyT4tBuCZ0'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Justin  8ans   - Swiss Voice Tour 2019 - Ta\u0308gipark , Wettingen\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/2qyT4tBuCZ0?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-46f8cd06e9d3175d0940f18947d5d919\">\n.flex_column.av-747ax-46f8cd06e9d3175d0940f18947d5d919{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-46f8cd06e9d3175d0940f18947d5d919 av_one_third  avia-builder-el-82  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-b299e0167865f47cdd0cc30d0bdcbaff avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/-2VVBQ7eKIc'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Konstantin  11ans   - Swiss Voice Tour 2019 - Ta\u0308gipark , Wettingen\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/-2VVBQ7eKIc?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-84  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-1a8e20dfd422795adb994ee0f189fcf9\">\n.flex_column.av-747ax-1a8e20dfd422795adb994ee0f189fcf9{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-1a8e20dfd422795adb994ee0f189fcf9 av_one_third  avia-builder-el-85  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-a64f725583ed1ebe724bf926373b08d8 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/1egs43-3Z9Y'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Lorena  15ans  - Swiss Voice Tour 2019 - Ta\u0308gipark , Wettingen\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/1egs43-3Z9Y?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-46f8cd06e9d3175d0940f18947d5d919\">\n.flex_column.av-747ax-46f8cd06e9d3175d0940f18947d5d919{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-46f8cd06e9d3175d0940f18947d5d919 av_one_third  avia-builder-el-87  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-272f87ea6f48159c4c9f63490ff8b1b7 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/drZ9qftu4s8'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Samira   10ans  - Swiss Voice Tour 2019 - Ta\u0308gipark , Wettingen\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/drZ9qftu4s8?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-46f8cd06e9d3175d0940f18947d5d919\">\n.flex_column.av-747ax-46f8cd06e9d3175d0940f18947d5d919{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-46f8cd06e9d3175d0940f18947d5d919 av_one_third  avia-builder-el-89  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-c8dc3adb385cf28c49882ef421a1212b avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/gkWWL4XGtMA'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Michael  12ans  - Swiss Voice Tour 2019 - Ta\u0308gipark , Wettingen\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/gkWWL4XGtMA?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-91  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-1a8e20dfd422795adb994ee0f189fcf9\">\n.flex_column.av-747ax-1a8e20dfd422795adb994ee0f189fcf9{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-1a8e20dfd422795adb994ee0f189fcf9 av_one_third  avia-builder-el-92  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-a30062120da21f8b40d0680c7c2aea57 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/zSGOsRwO4bU'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Manuela  13ans - Swiss Voice Tour 2019 - Ta\u0308gipark , Wettingen\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/zSGOsRwO4bU?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-46f8cd06e9d3175d0940f18947d5d919\">\n.flex_column.av-747ax-46f8cd06e9d3175d0940f18947d5d919{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-46f8cd06e9d3175d0940f18947d5d919 av_one_third  avia-builder-el-94  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-899f060f191a03223457cde5035010b6 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/IcxlXBRYfvY'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Aisha  12ans - Swiss Voice Tour 2019 - Ta\u0308gipark , Wettingen\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/IcxlXBRYfvY?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-46f8cd06e9d3175d0940f18947d5d919\">\n.flex_column.av-747ax-46f8cd06e9d3175d0940f18947d5d919{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-46f8cd06e9d3175d0940f18947d5d919 av_one_third  avia-builder-el-96  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-27faf73e3fa819cf012919f06d6d1a01 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/nxmbuISLMRM'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Nina   12ans  - Swiss Voice Tour 2019 - Ta\u0308gipark , Wettingen\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/nxmbuISLMRM?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-98  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-1a8e20dfd422795adb994ee0f189fcf9\">\n.flex_column.av-747ax-1a8e20dfd422795adb994ee0f189fcf9{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-1a8e20dfd422795adb994ee0f189fcf9 av_one_third  avia-builder-el-99  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-3a5a930f6932da94b87ff46ae9214d88 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/pTR5YBVhjS8'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Ilay 10ans - Swiss Voice Tour 2019 - Ta\u0308gipark , Wettingen\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/pTR5YBVhjS8?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-46f8cd06e9d3175d0940f18947d5d919\">\n.flex_column.av-747ax-46f8cd06e9d3175d0940f18947d5d919{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-46f8cd06e9d3175d0940f18947d5d919 av_one_third  avia-builder-el-101  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-44ada4cd8a1bab206bfc453c38425c17 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/jNb_1m8ubrE'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Marina.11ans - Swiss Voice Tour 2019 - Ta\u0308gipark , Wettingen\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/jNb_1m8ubrE?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-46f8cd06e9d3175d0940f18947d5d919\">\n.flex_column.av-747ax-46f8cd06e9d3175d0940f18947d5d919{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-46f8cd06e9d3175d0940f18947d5d919 av_one_third  avia-builder-el-103  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-8a84e0f6c55a4ddeb0b561c75952d989 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/M5NxsY39PJs'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Alessia   13ans- Swiss Voice Tour 2019 - Ta\u0308gipark , Wettingen\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/M5NxsY39PJs?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-105  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-1a8e20dfd422795adb994ee0f189fcf9\">\n.flex_column.av-747ax-1a8e20dfd422795adb994ee0f189fcf9{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-1a8e20dfd422795adb994ee0f189fcf9 av_one_third  avia-builder-el-106  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-9b91fd194777a6010e8a05d53d063fcb avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/tTtODnYBmpY'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Erlisa 14ans- Swiss Voice Tour 2019 - Ta\u0308gipark , Wettingen\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/tTtODnYBmpY?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-46f8cd06e9d3175d0940f18947d5d919\">\n.flex_column.av-747ax-46f8cd06e9d3175d0940f18947d5d919{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-46f8cd06e9d3175d0940f18947d5d919 av_one_third  avia-builder-el-108  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-a8e09667fd254e064c964e04d1a642b2 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/xB2sSGwLuzM'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Nevio 11 ans - Swiss Voice Tour 2019 - Ta\u0308gipark , Wettingen\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/xB2sSGwLuzM?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-46f8cd06e9d3175d0940f18947d5d919\">\n.flex_column.av-747ax-46f8cd06e9d3175d0940f18947d5d919{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-46f8cd06e9d3175d0940f18947d5d919 av_one_third  avia-builder-el-110  el_after_av_one_third  el_before_av_hr  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-916fa0567d72490d1d42270f4045458d avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/pB0O_O39KXI'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Leandra 10ans - Swiss Voice Tour 2019 - Ta\u0308gipark , Wettingen\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/pB0O_O39KXI?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38\">\n#top .hr.hr-invisible.av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38{\nheight:30px;\n}\n<\/style>\n<div  class='hr av-k7ngd4rx-674fbae84661cc2cc693a353e47e8e38 hr-invisible  avia-builder-el-112  el_after_av_one_third  el_before_av_one_third '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-1a8e20dfd422795adb994ee0f189fcf9\">\n.flex_column.av-747ax-1a8e20dfd422795adb994ee0f189fcf9{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-1a8e20dfd422795adb994ee0f189fcf9 av_one_third  avia-builder-el-113  el_after_av_hr  el_before_av_one_third  first flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-7c2c9622841ee69ce3a468cea19cc175 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/9TfkyBtoiLk'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"C\u00e9line 16ans  - Swiss Voice Tour 2019 - Ta\u0308gipark , Wettingen\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/9TfkyBtoiLk?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-46f8cd06e9d3175d0940f18947d5d919\">\n.flex_column.av-747ax-46f8cd06e9d3175d0940f18947d5d919{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-46f8cd06e9d3175d0940f18947d5d919 av_one_third  avia-builder-el-115  el_after_av_one_third  el_before_av_one_third  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-37aa5341c365561a931b7f23ed1bd865 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/xVErdVGsLLI'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Neha Sriram 12ans    - Swiss Voice Tour 2019 - Ta\u0308gipark , Wettingen\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/xVErdVGsLLI?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-747ax-46f8cd06e9d3175d0940f18947d5d919\">\n.flex_column.av-747ax-46f8cd06e9d3175d0940f18947d5d919{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-747ax-46f8cd06e9d3175d0940f18947d5d919 av_one_third  avia-builder-el-117  el_after_av_one_third  avia-builder-el-last  flex_column_div av-zero-column-padding  '     ><div  class='avia-video av-k7nga4og-eb27687e2dc3f0e255e6d829ecedf493 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/youtu.be\/cdy0mkrfD5Q'><script type='text\/html' class='av-video-tmpl'><div class='avia-iframe-wrap'><iframe loading=\"lazy\" title=\"Maanasa Sriram 14ans   - Swiss Voice Tour 2019 - Ta\u0308gipark , Wettingen\" width=\"1500\" height=\"844\" src=\"https:\/\/www.youtube.com\/embed\/cdy0mkrfD5Q?feature=oembed&autoplay=0&loop=0&controls=1&mute=0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":4314,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-6070","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>T\u00c4GIPARK - Kids - Swiss Voice Tour<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"T\u00c4GIPARK - Kids - Swiss Voice Tour\" \/>\n<meta property=\"og:url\" content=\"https:\/\/swissvoicetour.smartfox-adtech.ch\/de\/staffeln\/staffel-6\/taegipark-kids\/\" \/>\n<meta property=\"og:site_name\" content=\"Swiss Voice Tour\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-16T12:59:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"47\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/swissvoicetour.smartfox-adtech.ch\/de\/staffeln\/staffel-6\/taegipark-kids\/\",\"url\":\"https:\/\/swissvoicetour.smartfox-adtech.ch\/de\/staffeln\/staffel-6\/taegipark-kids\/\",\"name\":\"T\u00c4GIPARK - Kids - Swiss Voice Tour\",\"isPartOf\":{\"@id\":\"https:\/\/swissvoicetour.smartfox-adtech.ch\/#website\"},\"datePublished\":\"2020-04-16T10:06:37+00:00\",\"dateModified\":\"2020-04-16T12:59:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/swissvoicetour.smartfox-adtech.ch\/de\/staffeln\/staffel-6\/taegipark-kids\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/swissvoicetour.smartfox-adtech.ch\/de\/staffeln\/staffel-6\/taegipark-kids\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/swissvoicetour.smartfox-adtech.ch\/de\/staffeln\/staffel-6\/taegipark-kids\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/swissvoicetour.smartfox-adtech.ch\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"STAFFELN\",\"item\":\"https:\/\/swissvoicetour.smartfox-adtech.ch\/de\/staffeln\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"6. Staffel\",\"item\":\"https:\/\/swissvoicetour.smartfox-adtech.ch\/de\/staffeln\/staffel-6\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"T\u00c4GIPARK &#8211; Kids\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/swissvoicetour.smartfox-adtech.ch\/#website\",\"url\":\"https:\/\/swissvoicetour.smartfox-adtech.ch\/\",\"name\":\"Swiss Voice Tour\",\"description\":\"Willkommen auf der offiziellen Seite der Swiss Voice Tour\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/swissvoicetour.smartfox-adtech.ch\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"T\u00c4GIPARK - Kids - Swiss Voice Tour","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_title":"T\u00c4GIPARK - Kids - Swiss Voice Tour","og_url":"https:\/\/swissvoicetour.smartfox-adtech.ch\/de\/staffeln\/staffel-6\/taegipark-kids\/","og_site_name":"Swiss Voice Tour","article_modified_time":"2020-04-16T12:59:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"47\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/swissvoicetour.smartfox-adtech.ch\/de\/staffeln\/staffel-6\/taegipark-kids\/","url":"https:\/\/swissvoicetour.smartfox-adtech.ch\/de\/staffeln\/staffel-6\/taegipark-kids\/","name":"T\u00c4GIPARK - Kids - Swiss Voice Tour","isPartOf":{"@id":"https:\/\/swissvoicetour.smartfox-adtech.ch\/#website"},"datePublished":"2020-04-16T10:06:37+00:00","dateModified":"2020-04-16T12:59:50+00:00","breadcrumb":{"@id":"https:\/\/swissvoicetour.smartfox-adtech.ch\/de\/staffeln\/staffel-6\/taegipark-kids\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/swissvoicetour.smartfox-adtech.ch\/de\/staffeln\/staffel-6\/taegipark-kids\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/swissvoicetour.smartfox-adtech.ch\/de\/staffeln\/staffel-6\/taegipark-kids\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/swissvoicetour.smartfox-adtech.ch\/de\/"},{"@type":"ListItem","position":2,"name":"STAFFELN","item":"https:\/\/swissvoicetour.smartfox-adtech.ch\/de\/staffeln\/"},{"@type":"ListItem","position":3,"name":"6. Staffel","item":"https:\/\/swissvoicetour.smartfox-adtech.ch\/de\/staffeln\/staffel-6\/"},{"@type":"ListItem","position":4,"name":"T\u00c4GIPARK &#8211; Kids"}]},{"@type":"WebSite","@id":"https:\/\/swissvoicetour.smartfox-adtech.ch\/#website","url":"https:\/\/swissvoicetour.smartfox-adtech.ch\/","name":"Swiss Voice Tour","description":"Willkommen auf der offiziellen Seite der Swiss Voice Tour","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/swissvoicetour.smartfox-adtech.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/swissvoicetour.smartfox-adtech.ch\/de\/wp-json\/wp\/v2\/pages\/6070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/swissvoicetour.smartfox-adtech.ch\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/swissvoicetour.smartfox-adtech.ch\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/swissvoicetour.smartfox-adtech.ch\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/swissvoicetour.smartfox-adtech.ch\/de\/wp-json\/wp\/v2\/comments?post=6070"}],"version-history":[{"count":3,"href":"https:\/\/swissvoicetour.smartfox-adtech.ch\/de\/wp-json\/wp\/v2\/pages\/6070\/revisions"}],"predecessor-version":[{"id":6265,"href":"https:\/\/swissvoicetour.smartfox-adtech.ch\/de\/wp-json\/wp\/v2\/pages\/6070\/revisions\/6265"}],"up":[{"embeddable":true,"href":"https:\/\/swissvoicetour.smartfox-adtech.ch\/de\/wp-json\/wp\/v2\/pages\/4314"}],"wp:attachment":[{"href":"https:\/\/swissvoicetour.smartfox-adtech.ch\/de\/wp-json\/wp\/v2\/media?parent=6070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}